{"id":556,"date":"2021-08-27T13:30:46","date_gmt":"2021-08-27T13:30:46","guid":{"rendered":"http:\/\/dummy.xtemos.com\/woodmart2\/elementor\/?post_type=portfolio&amp;p=556"},"modified":"2021-08-27T13:30:46","modified_gmt":"2021-08-27T13:30:46","slug":"netus-eu-mollis-hac-dignis","status":"publish","type":"portfolio","link":"https:\/\/rxhealthcare.in\/index.php\/portfolio\/netus-eu-mollis-hac-dignis\/","title":{"rendered":"Netus eu mollis hac dignis"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"556\" class=\"elementor elementor-556\">\n\t\t\t\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-adf0fc8 elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"adf0fc8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-d9aa9a8\" data-id=\"d9aa9a8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5015f24 wd-video-theme-style elementor-widget elementor-widget-video\" data-id=\"5015f24\" data-element_type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/rxhealthcare.in\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/post-1-image-5.jpg&quot;,&quot;id&quot;:212,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;}}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.15.0 - 31-07-2023 *\/\n.elementor-widget-video .elementor-widget-container{overflow:hidden;transform:translateZ(0)}.elementor-widget-video .elementor-wrapper{aspect-ratio:var(--video-aspect-ratio)}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{height:100%;width:100%;display:flex;border:none;background-color:#000}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-wrapper{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .elementor-open-inline .elementor-custom-embed-image-overlay{position:absolute;top:0;right:0;bottom:0;left:0;background-size:cover;background-position:50%}.elementor-widget-video .elementor-custom-embed-image-overlay{cursor:pointer;text-align:center}.elementor-widget-video .elementor-custom-embed-image-overlay:hover .elementor-custom-embed-play i{opacity:1}.elementor-widget-video .elementor-custom-embed-image-overlay img{display:block;width:100%;aspect-ratio:var(--video-aspect-ratio);-o-object-fit:cover;object-fit:cover;-o-object-position:center center;object-position:center center}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-custom-embed-image-overlay{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-custom-embed-image-overlay img{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .e-hosted-video .elementor-video{-o-object-fit:cover;object-fit:cover}.e-con-inner>.elementor-widget-video,.e-con>.elementor-widget-video{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen title=\"vimeo Video Player\" src=\"https:\/\/player.vimeo.com\/video\/235215203?color&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=1&amp;portrait=1&amp;byline=1#t=\"><\/iframe>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/rxhealthcare.in\/wp-content\/uploads\/2021\/08\/post-1-image-5.jpg);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Play Video\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Play Video<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-71ce83f\" data-id=\"71ce83f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-5e35a2f elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"5e35a2f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f71717b\" data-id=\"f71717b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0430195 elementor-widget elementor-widget-wd_title\" data-id=\"0430195\" data-element_type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"title-wrapper set-mb-s reset-last-child wd-title-color-default wd-title-style-default wd-title-size-large text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-xxl\">Our Latest Work<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0553f3e elementor-widget elementor-widget-wd_text_block\" data-id=\"0553f3e\" data-element_type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left color-#989898 color-scheme-custom\">\n\t\t\t\n\t\t\t<p>WE ARE CREATIVE AGENCY<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7a029c elementor-widget elementor-widget-wd_text_block\" data-id=\"e7a029c\" data-element_type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p>Accum luctus dolor sit amet, consectetuer adipiscing elit, sed diam nonummy nibh euismod tincidunt ut laoreet dolore magna aliquam erat volutpat. Ut wisi enim ad minim veniam.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bc0315 elementor-widget__width-initial elementor-widget elementor-widget-wd_infobox\" data-id=\"4bc0315\" data-element_type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-left box-icon-align-top box-style-base color-scheme-\" >\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title title box-title-style-underlined wd-fontsize-s\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\tCLIENT\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner set-cont-mb-s reset-last-child\"\n\t\t\t\t\t\t data-elementor-setting-key=\"content\">\n\t\t\t\t\t\t<p>MINDSPARKLE SHOP<\/p>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd4ebe2 elementor-widget__width-initial elementor-widget elementor-widget-wd_infobox\" data-id=\"bd4ebe2\" data-element_type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-left box-icon-align-top box-style-base color-scheme-\" >\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title title box-title-style-underlined wd-fontsize-s\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\tCLIENT\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner set-cont-mb-s reset-last-child\"\n\t\t\t\t\t\t data-elementor-setting-key=\"content\">\n\t\t\t\t\t\t<p>MINDSPARKLE SHOP<\/p>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ce34f7 elementor-widget__width-initial elementor-widget elementor-widget-wd_infobox\" data-id=\"4ce34f7\" data-element_type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-left box-icon-align-top box-style-base color-scheme-\" >\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title title box-title-style-underlined wd-fontsize-s\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\tDESIGNER\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner set-cont-mb-s reset-last-child\"\n\t\t\t\t\t\t data-elementor-setting-key=\"content\">\n\t\t\t\t\t\t<p>JOHN DOE<\/p>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59ddcf5 elementor-widget__width-initial elementor-widget elementor-widget-wd_infobox\" data-id=\"59ddcf5\" data-element_type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-left box-icon-align-top box-style-base color-scheme-\" >\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title title box-title-style-underlined wd-fontsize-s\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\tWEBSITE\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner set-cont-mb-s reset-last-child\"\n\t\t\t\t\t\t data-elementor-setting-key=\"content\">\n\t\t\t\t\t\t<p>XTEMOS.COM\/WOOD<\/p>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-d3e0d69 wd-section-stretch elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d3e0d69\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-e41985e\" data-id=\"e41985e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21d3d82 elementor-widget elementor-widget-wd_title\" data-id=\"21d3d82\" data-element_type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"title-wrapper set-mb-s reset-last-child wd-title-color-default wd-title-style-default wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l\">PROJECT WITH DESCRIPTION EXAMPLE<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-ca79601 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"ca79601\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-48909b4\" data-id=\"48909b4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-05b26f0 elementor-widget elementor-widget-wd_text_block\" data-id=\"05b26f0\" data-element_type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p><em>Commodo scelerisque facilisis enim ante habitant suspendisse fringilla ad a primis malesuada curabitur ullamcorper tellus fermentum.<\/em><\/p><p>Eget tempus praesent nec vestibulum condimentum dis suscipit phasellus viverra suscipit vestibulum nunc feugiat vestibulum eget a semper id elit nullam vestibulum maecenas convallis volutpat porttitor vivamus et. Nascetur laoreet ipsum placerat odio a dolor torquent adipiscing ac aliquam mollis proin venenatis ullamcorper imperdiet non ante a.<\/p><p>Ut a parturient ad vestibulum lectus varius dignissim fusce mi posuere ante vivamus vestibulum parturient sed. A sit fermentum purus a ullamcorper a condimentum at malesuada.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-18856aa\" data-id=\"18856aa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8144c53 elementor-widget elementor-widget-wd_text_block\" data-id=\"8144c53\" data-element_type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p>Varius a ullamcorper duis elit conubia urna fermentum vel eros venenatis donec scelerisque nam leo sem condimentum eu sociis. Suspendisse egestas a vulputate ante scelerisque aliquam suspendisse metus a a condimentum eu vestibulum vestibulum dui posuere\u00a0tincidunt blandit.<\/p><h5 style=\"color: #666666;\">Potenti penatibus quisque<\/h5><p>Blandit scelerisque condimentum sit at adipiscing. Adipiscing vestibulum suspendisse nisi vene natis iaculis ridiculus adipis cing habitasse neque ad at hendrerit diam facilisi semper. Potenti pen atibus quisque suspen disse fusce sociosqu lobor tis eget neque nascetur \u00a0posuere nisi\u00a0adipiscing condim entum in vulputate auctor a sem viverra.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3b5c194\" data-id=\"3b5c194\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73d0e99 elementor-widget elementor-widget-wd_title\" data-id=\"73d0e99\" data-element_type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"title-wrapper set-mb-s reset-last-child wd-title-color-default wd-title-style-default wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l\">FAQs<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c70384 elementor-widget elementor-widget-accordion\" data-id=\"6c70384\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.15.0 - 31-07-2023 *\/\n.elementor-accordion{text-align:left}.elementor-accordion .elementor-accordion-item{border:1px solid #d5d8dc}.elementor-accordion .elementor-accordion-item+.elementor-accordion-item{border-top:none}.elementor-accordion .elementor-tab-title{margin:0;padding:15px 20px;font-weight:700;line-height:1;cursor:pointer;outline:none}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{display:inline-block;width:1.5em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon svg{width:1em;height:1em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-right{float:right;text-align:right}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-left{float:left;text-align:left}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-closed{display:block}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-opened,.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-closed{display:none}.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-opened{display:block}.elementor-accordion .elementor-tab-content{display:none;padding:15px 20px;border-top:1px solid #d5d8dc}@media (max-width:767px){.elementor-accordion .elementor-tab-title{padding:12px 15px}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{width:1.2em}.elementor-accordion .elementor-tab-content{padding:7px 15px}}.e-con-inner>.elementor-widget-accordion,.e-con>.elementor-widget-accordion{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1131\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1131\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">How this can be done for me?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1131\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1131\"><p>Sodales quisque in torquent a consectetur lobortis vestibulum consectetur metus a a interdum odio orci a est parturient nisi pharetra vivamus a commodo tellus. Est non arcu a.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1132\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1132\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Justo ad nullam scelerisque fel<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1132\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1132\"><p>Sodales quisque in torquent a consectetur lobortis vestibulum consectetur metus a a interdum odio orci a est parturient nisi pharetra vivamus a commodo tellus. Est non arcu a.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1133\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1133\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Porta nec aenean pellentesqu<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1133\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1133\"><p>Sodales quisque in torquent a consectetur lobortis vestibulum consectetur metus a a interdum odio orci a est parturient nisi pharetra vivamus a commodo tellus. Est non arcu a.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1134\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1134\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Erat sagittis mollis rhoncus<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1134\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1134\"><p>Sodales quisque in torquent a consectetur lobortis vestibulum consectetur metus a a interdum odio orci a est parturient nisi pharetra vivamus a commodo tellus. Est non arcu a.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-4a0e3c9 elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"4a0e3c9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-717e4aa\" data-id=\"717e4aa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-fd793d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"fd793d8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-26259b5\" data-id=\"26259b5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e7b9ba elementor-widget elementor-widget-wd_infobox\" data-id=\"0e7b9ba\" data-element_type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-center box-icon-align-top box-style-base color-scheme- cursor-pointer\" onclick=\"window.location.href='#'\">\n\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"info-svg-wrapper info-icon\" style=\"width:58px; height:58px;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" version=\"1.1\" id=\"svg-1095\" x=\"0px\" y=\"0px\" viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\"> <g> <path d=\"M30,0C13.458,0,0,13.458,0,30s13.458,30,30,30s30-13.458,30-30S46.542,0,30,0z M30,58C14.561,58,2,45.439,2,30 S14.561,2,30,2s28,12.561,28,28S45.439,58,30,58z\"><\/path> <path d=\"M30,6c-0.552,0-1,0.447-1,1v23H14c-0.552,0-1,0.447-1,1s0.448,1,1,1h16c0.552,0,1-0.447,1-1V7C31,6.447,30.552,6,30,6z\"><\/path> <\/g> <g> <\/g> <g> <\/g> <g> <\/g> <g> <\/g> <g> <\/g> <g> <\/g> <g> <\/g> <g> <\/g> <g> <\/g> <g> <\/g> <g> <\/g> <g> <\/g> <g> <\/g> <g> <\/g> <g> <\/g> <\/svg> <\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title title box-title-style-default wd-fontsize-m\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\tTACITIRS LOBORTIS\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner set-cont-mb-s reset-last-child\"\n\t\t\t\t\t\t data-elementor-setting-key=\"content\">\n\t\t\t\t\t\t<p>Elis mus a habitant\u00a0mi suspendisse adipiscing ultricies torquent id urna.<\/p>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2dba99 elementor-widget elementor-widget-wd_infobox\" data-id=\"e2dba99\" data-element_type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-center box-icon-align-top box-style-base color-scheme- cursor-pointer\" onclick=\"window.location.href='#'\">\n\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"info-svg-wrapper info-icon\" style=\"width:58px; height:58px;\"><svg id=\"svg-9133\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" version=\"1.1\" id=\"svg-1070\" x=\"0px\" y=\"0px\" viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\"><g><path d=\"M58.978,37.765c0.001-0.003,0-0.007,0.001-0.01C59.641,35.28,60,32.681,60,30s-0.359-5.28-1.022-7.755&#10;&#9;&#9;c-0.001-0.003,0-0.007,0-0.007c-0.002-0.007-0.005-0.01-0.006-0.014c-0.681-2.533-1.687-4.933-2.969-7.156&#10;&#9;&#9;c-0.011-0.022-0.011-0.047-0.023-0.069c-0.012-0.021-0.034-0.033-0.047-0.054c-1.298-2.228-2.869-4.277-4.677-6.094&#10;&#9;&#9;c-0.017-0.02-0.024-0.046-0.043-0.065s-0.045-0.026-0.065-0.043c-1.817-1.808-3.866-3.379-6.094-4.677&#10;&#9;&#9;C45.034,4.053,45.022,4.032,45,4.02c-0.022-0.013-0.047-0.013-0.07-0.023c-2.223-1.281-4.622-2.288-7.155-2.969&#10;&#9;&#9;c-0.004-0.001-0.007-0.004-0.01-0.005c-0.003-0.001-0.007,0-0.01,0C35.28,0.359,32.681,0,30,0s-5.28,0.359-7.755,1.022&#10;&#9;&#9;c-0.003,0.001-0.007,0-0.01,0c-0.004,0.001-0.007,0.004-0.01,0.005c-2.533,0.68-4.932,1.687-7.155,2.968&#10;&#9;&#9;C15.047,4.007,15.022,4.007,15,4.02c-0.022,0.012-0.034,0.034-0.054,0.047c-2.228,1.298-4.277,2.869-6.094,4.677&#10;&#9;&#9;c-0.02,0.017-0.046,0.024-0.065,0.043S8.761,8.832,8.744,8.852c-1.807,1.817-3.379,3.866-4.677,6.094&#10;&#9;&#9;C4.053,14.967,4.032,14.979,4.02,15c-0.013,0.022-0.012,0.046-0.023,0.069c-1.282,2.223-2.288,4.623-2.969,7.156&#10;&#9;&#9;c-0.001,0.004-0.004,0.006-0.005,0.01c0,0,0,0.007-0.001,0.01C0.359,24.72,0,27.319,0,30s0.359,5.28,1.022,7.755&#10;&#9;&#9;c0.001,0.003,0,0.007,0.001,0.01c0.001,0.005,0.005,0.008,0.006,0.013c0.681,2.532,1.687,4.931,2.968,7.154&#10;&#9;&#9;C4.007,44.954,4.007,44.978,4.02,45c0.018,0.031,0.044,0.055,0.065,0.083c1.295,2.216,2.86,4.256,4.66,6.064&#10;&#9;&#9;c0.017,0.02,0.024,0.046,0.043,0.065s0.045,0.026,0.065,0.043c1.816,1.807,3.864,3.377,6.091,4.675&#10;&#9;&#9;c0.021,0.015,0.034,0.037,0.057,0.05c0.034,0.02,0.071,0.029,0.107,0.044c2.213,1.271,4.599,2.27,7.118,2.947&#10;&#9;&#9;c0.004,0.001,0.007,0.004,0.01,0.005c0.005,0.001,0.01,0.001,0.015,0.002C24.724,59.642,27.32,60,30,60s5.276-0.358,7.75-1.021&#10;&#9;&#9;c0.005-0.001,0.01-0.001,0.015-0.002c0.004-0.001,0.007-0.004,0.01-0.005c2.519-0.677,4.905-1.676,7.118-2.947&#10;&#9;&#9;c0.036-0.015,0.073-0.024,0.107-0.044c0.023-0.013,0.036-0.036,0.057-0.05c2.226-1.298,4.275-2.868,6.091-4.675&#10;&#9;&#9;c0.02-0.017,0.046-0.024,0.065-0.043s0.026-0.045,0.043-0.065c1.799-1.809,3.365-3.848,4.66-6.064&#10;&#9;&#9;c0.021-0.029,0.047-0.052,0.065-0.083c0.013-0.022,0.012-0.046,0.023-0.069c1.281-2.222,2.287-4.621,2.968-7.154&#10;&#9;&#9;C58.973,37.773,58.976,37.77,58.978,37.765z M54.855,37.695l1.915,0.513c-0.526,1.713-1.215,3.356-2.044,4.912l-1.709-0.987&#10;&#9;&#9;c-0.478-0.276-1.09-0.113-1.366,0.366c-0.276,0.479-0.112,1.09,0.366,1.366l1.704,0.984c-0.947,1.508-2.033,2.919-3.241,4.216&#10;&#9;&#9;l-1.388-1.388c-0.391-0.391-1.023-0.391-1.414,0s-0.391,1.023,0,1.414l1.388,1.388c-1.297,1.208-2.708,2.294-4.216,3.241&#10;&#9;&#9;l-0.984-1.705c-0.277-0.479-0.89-0.643-1.366-0.366c-0.479,0.276-0.643,0.888-0.366,1.366l0.987,1.709&#10;&#9;&#9;c-1.557,0.829-3.199,1.518-4.912,2.044l-0.513-1.915c-0.143-0.534-0.689-0.851-1.225-0.707c-0.533,0.143-0.85,0.691-0.707,1.225&#10;&#9;&#9;l0.512,1.909c-1.705,0.392-3.468,0.628-5.275,0.692V54c0-0.553-0.447-1-1-1s-1,0.447-1,1v3.975c-1.807-0.064-3.57-0.3-5.275-0.692&#10;&#9;&#9;l0.512-1.909c0.143-0.533-0.174-1.082-0.707-1.225c-0.533-0.143-1.082,0.173-1.225,0.707l-0.513,1.915&#10;&#9;&#9;c-1.713-0.526-3.355-1.215-4.912-2.044l0.987-1.709c0.276-0.479,0.112-1.09-0.366-1.366s-1.089-0.112-1.366,0.366l-0.984,1.705&#10;&#9;&#9;c-1.508-0.947-2.919-2.033-4.216-3.241l1.388-1.388c0.391-0.391,0.391-1.023,0-1.414s-1.023-0.391-1.414,0L9.52,49.066&#10;&#9;&#9;c-1.208-1.297-2.294-2.708-3.241-4.216l1.704-0.984C8.462,43.59,8.626,42.979,8.35,42.5c-0.277-0.479-0.889-0.643-1.366-0.366&#10;&#9;&#9;l-1.709,0.987c-0.829-1.557-1.518-3.199-2.044-4.912l1.915-0.513c0.533-0.143,0.85-0.691,0.707-1.225&#10;&#9;&#9;c-0.142-0.534-0.69-0.852-1.225-0.707l-1.909,0.511C2.326,34.57,2.089,32.807,2.025,31H6c0.553,0,1-0.447,1-1s-0.447-1-1-1H2.025&#10;&#9;&#9;c0.064-1.807,0.3-3.57,0.692-5.275l1.909,0.511c0.087,0.023,0.174,0.034,0.26,0.034c0.441,0,0.846-0.294,0.965-0.741&#10;&#9;&#9;c0.143-0.533-0.174-1.082-0.707-1.225L3.23,21.792c0.526-1.713,1.215-3.356,2.044-4.912l1.709,0.987&#10;&#9;&#9;C7.141,17.957,7.312,18,7.482,18c0.346,0,0.682-0.179,0.867-0.5c0.276-0.479,0.112-1.09-0.366-1.366L6.279,15.15&#10;&#9;&#9;c0.947-1.508,2.033-2.919,3.241-4.216l1.388,1.388c0.195,0.195,0.451,0.293,0.707,0.293s0.512-0.098,0.707-0.293&#10;&#9;&#9;c0.391-0.391,0.391-1.023,0-1.414L10.934,9.52c1.297-1.208,2.708-2.294,4.216-3.241l0.984,1.704c0.186,0.321,0.521,0.5,0.867,0.5&#10;&#9;&#9;c0.17,0,0.342-0.043,0.499-0.134c0.479-0.276,0.643-0.888,0.366-1.366l-0.987-1.709c1.557-0.829,3.199-1.518,4.912-2.044&#10;&#9;&#9;l0.513,1.915c0.119,0.447,0.523,0.741,0.965,0.741c0.086,0,0.173-0.011,0.26-0.034c0.533-0.143,0.85-0.691,0.707-1.225&#10;&#9;&#9;l-0.512-1.909C25.43,2.326,27.193,2.089,29,2.025V6c0,0.553,0.447,1,1,1s1-0.447,1-1V2.025c1.807,0.064,3.57,0.3,5.275,0.692&#10;&#9;&#9;l-0.512,1.909c-0.143,0.533,0.174,1.082,0.707,1.225c0.087,0.023,0.174,0.034,0.26,0.034c0.441,0,0.846-0.294,0.965-0.741&#10;&#9;&#9;l0.513-1.915c1.713,0.526,3.356,1.215,4.912,2.044l-0.987,1.709c-0.276,0.479-0.112,1.09,0.366,1.366&#10;&#9;&#9;c0.157,0.091,0.329,0.134,0.499,0.134c0.346,0,0.682-0.179,0.867-0.5l0.984-1.704c1.508,0.947,2.919,2.033,4.216,3.241&#10;&#9;&#9;l-1.388,1.388c-0.391,0.391-0.391,1.023,0,1.414c0.195,0.195,0.451,0.293,0.707,0.293s0.512-0.098,0.707-0.293l1.388-1.388&#10;&#9;&#9;c1.208,1.297,2.294,2.708,3.241,4.216l-1.704,0.984c-0.479,0.276-0.643,0.888-0.366,1.366c0.186,0.321,0.521,0.5,0.867,0.5&#10;&#9;&#9;c0.17,0,0.342-0.043,0.499-0.134l1.709-0.987c0.829,1.557,1.518,3.199,2.044,4.912l-1.915,0.513&#10;&#9;&#9;c-0.533,0.143-0.85,0.691-0.707,1.225c0.119,0.447,0.523,0.741,0.965,0.741c0.086,0,0.173-0.011,0.26-0.034l1.909-0.511&#10;&#9;&#9;c0.392,1.705,0.629,3.468,0.692,5.275H54c-0.553,0-1,0.447-1,1s0.447,1,1,1h3.975c-0.064,1.807-0.3,3.57-0.692,5.275l-1.909-0.511&#10;&#9;&#9;c-0.532-0.143-1.082,0.173-1.225,0.707C54.006,37.004,54.322,37.553,54.855,37.695z\"><\/path><path d=\"M41,29h-7.142c-0.364-1.399-1.459-2.495-2.858-2.858V13c0-0.553-0.447-1-1-1s-1,0.447-1,1v13.142&#10;&#9;&#9;c-1.721,0.447-3,1.999-3,3.858c0,2.206,1.794,4,4,4c1.859,0,3.411-1.28,3.858-3H41c0.553,0,1-0.447,1-1S41.553,29,41,29z M30,32&#10;&#9;&#9;c-1.103,0-2-0.897-2-2s0.897-2,2-2s2,0.897,2,2S31.103,32,30,32z\"><\/path><path d=\"M30,35c-4.411,0-8,3.589-8,8s3.589,8,8,8s8-3.589,8-8S34.411,35,30,35z M30,49c-3.309,0-6-2.691-6-6s2.691-6,6-6&#10;&#9;&#9;s6,2.691,6,6S33.309,49,30,49z\"><\/path><path d=\"M27.707,39.293c-0.391-0.391-1.023-0.391-1.414,0s-0.391,1.023,0,1.414l3,3C29.488,43.902,29.744,44,30,44&#10;&#9;&#9;s0.512-0.098,0.707-0.293c0.391-0.391,0.391-1.023,0-1.414L27.707,39.293z\"><\/path><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><\/svg> <\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title title box-title-style-default wd-fontsize-m\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\tVESTIBULUM MOLLIS\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner set-cont-mb-s reset-last-child\"\n\t\t\t\t\t\t data-elementor-setting-key=\"content\">\n\t\t\t\t\t\t<p>Blandit nibh at accumsan a a sed et diam himenaeos aliquet ad sagittis.<\/p>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6d0bc90\" data-id=\"6d0bc90\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-054ef71 elementor-widget elementor-widget-wd_infobox\" data-id=\"054ef71\" data-element_type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-center box-icon-align-top box-style-base color-scheme- cursor-pointer\" onclick=\"window.location.href='#'\">\n\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"info-svg-wrapper info-icon\" style=\"width:58px; height:58px;\"><svg id=\"svg-9646\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" version=\"1.1\" id=\"svg-7818\" x=\"0px\" y=\"0px\" viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\"><g><path d=\"M30,0c-0.553,0-1,0.447-1,1v13.292c0,0.553,0.447,1,1,1s1-0.447,1-1V2.018C45.979,2.546,58,14.896,58,30&#10;&#9;&#9;c0,15.439-12.561,28-28,28S2,45.439,2,30c0-7.46,2.9-14.479,8.166-19.764c0.391-0.392,0.389-1.024-0.002-1.414&#10;&#9;&#9;C9.772,8.434,9.14,8.434,8.75,8.824C3.107,14.486,0,22.007,0,30c0,16.542,13.458,30,30,30s30-13.458,30-30S46.542,0,30,0z\"><\/path><path d=\"M28.555,33.532c0.614,0.845,1.563,1.376,2.604,1.457C31.252,34.997,31.345,35,31.437,35c0.942,0,1.848-0.372,2.519-1.044&#10;&#9;&#9;c0.737-0.737,1.114-1.756,1.033-2.797s-0.612-1.99-1.459-2.606l-12.944-9.363c-0.396-0.286-0.945-0.242-1.293,0.104&#10;&#9;&#9;c-0.348,0.348-0.391,0.896-0.104,1.293L28.555,33.532z M32.355,30.172c0.371,0.27,0.604,0.687,0.64,1.144&#10;&#9;&#9;c0.036,0.456-0.13,0.903-0.453,1.227c-0.324,0.323-0.779,0.488-1.228,0.453c-0.456-0.035-0.873-0.269-1.141-0.637l-5.713-7.897&#10;&#9;&#9;L32.355,30.172z\"><\/path><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><\/svg> <\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title title box-title-style-default wd-fontsize-m\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\tPOSUERE ULLAMCPER\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner set-cont-mb-s reset-last-child\"\n\t\t\t\t\t\t data-elementor-setting-key=\"content\">\n\t\t\t\t\t\t<p>Vestibulum feugiat a volutpat dis cum primis\u00a0ultricies massa\u00a0taciti lobortis.<\/p>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2610049 elementor-widget elementor-widget-wd_infobox\" data-id=\"2610049\" data-element_type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-center box-icon-align-top box-style-base color-scheme- cursor-pointer\" onclick=\"window.location.href='#'\">\n\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"info-svg-wrapper info-icon\" style=\"width:58px; height:58px;\"><svg id=\"svg-6445\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" version=\"1.1\" id=\"svg-4282\" x=\"0px\" y=\"0px\" viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\"><g><path d=\"M30,0C13.458,0,0,13.458,0,30s13.458,30,30,30s30-13.458,30-30S46.542,0,30,0z M30,58C14.561,58,2,45.439,2,30&#10;&#9;&#9;S14.561,2,30,2s28,12.561,28,28S45.439,58,30,58z\"><\/path><path d=\"M31,26.021V15.879c0-0.553-0.448-1-1-1s-1,0.447-1,1v10.142c-1.399,0.364-2.494,1.459-2.858,2.858H19c-0.552,0-1,0.447-1,1&#10;&#9;&#9;s0.448,1,1,1h7.142c0.447,1.72,2,3,3.858,3c2.206,0,4-1.794,4-4C34,28.02,32.72,26.468,31,26.021z M30,31.879c-1.103,0-2-0.897-2-2&#10;&#9;&#9;s0.897-2,2-2s2,0.897,2,2S31.103,31.879,30,31.879z\"><\/path><path d=\"M30,9.879c0.552,0,1-0.447,1-1v-1c0-0.553-0.448-1-1-1s-1,0.447-1,1v1C29,9.432,29.448,9.879,30,9.879z\"><\/path><path d=\"M30,49.879c-0.552,0-1,0.447-1,1v1c0,0.553,0.448,1,1,1s1-0.447,1-1v-1C31,50.326,30.552,49.879,30,49.879z\"><\/path><path d=\"M52,28.879h-1c-0.552,0-1,0.447-1,1s0.448,1,1,1h1c0.552,0,1-0.447,1-1S52.552,28.879,52,28.879z\"><\/path><path d=\"M9,28.879H8c-0.552,0-1,0.447-1,1s0.448,1,1,1h1c0.552,0,1-0.447,1-1S9.552,28.879,9,28.879z\"><\/path><path d=\"M44.849,13.615l-0.707,0.707c-0.391,0.391-0.391,1.023,0,1.414c0.195,0.195,0.451,0.293,0.707,0.293&#10;&#9;&#9;s0.512-0.098,0.707-0.293l0.707-0.707c0.391-0.391,0.391-1.023,0-1.414S45.24,13.225,44.849,13.615z\"><\/path><path d=\"M14.444,44.021l-0.707,0.707c-0.391,0.391-0.391,1.023,0,1.414c0.195,0.195,0.451,0.293,0.707,0.293&#10;&#9;&#9;s0.512-0.098,0.707-0.293l0.707-0.707c0.391-0.391,0.391-1.023,0-1.414S14.834,43.631,14.444,44.021z\"><\/path><path d=\"M45.556,44.021c-0.391-0.391-1.023-0.391-1.414,0s-0.391,1.023,0,1.414l0.707,0.707c0.195,0.195,0.451,0.293,0.707,0.293&#10;&#9;&#9;s0.512-0.098,0.707-0.293c0.391-0.391,0.391-1.023,0-1.414L45.556,44.021z\"><\/path><path d=\"M15.151,13.615c-0.391-0.391-1.023-0.391-1.414,0s-0.391,1.023,0,1.414l0.707,0.707c0.195,0.195,0.451,0.293,0.707,0.293&#10;&#9;&#9;s0.512-0.098,0.707-0.293c0.391-0.391,0.391-1.023,0-1.414L15.151,13.615z\"><\/path><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><\/svg> <\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title title box-title-style-default wd-fontsize-m\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\tLITORA PARTURIENT\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner set-cont-mb-s reset-last-child\"\n\t\t\t\t\t\t data-elementor-setting-key=\"content\">\n\t\t\t\t\t\t<p>Egestas a mi a faucibus vestibulum vestibulum nam aliquet\u00a0adipiscing.<\/p>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fde337b\" data-id=\"fde337b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-199241f elementor-widget elementor-widget-wd_images_gallery\" data-id=\"199241f\" data-element_type=\"widget\" data-widget_type=\"wd_images_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wd-images-gallery wd-justify-center wd-items-middle view-grid photoswipe-images\" >\n\t\t\t<div class=\"gallery-images row wd-spacing-6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item  col-lg-6 col-md-6 col-12\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/rxhealthcare.in\/wp-content\/uploads\/2021\/08\/post-3-gallery-3-min.jpg\"data-width=\"450\" data-height=\"700\" data-index=\"1\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/rxhealthcare.in\/wp-content\/uploads\/elementor\/thumbs\/post-3-gallery-3-min-qablpy2wt654o4q7xf7oka8wdagfyek58z1e0ommra.jpg\"alt=\"post-3-gallery-3-min\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item  col-lg-6 col-md-6 col-12\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/rxhealthcare.in\/wp-content\/uploads\/2021\/08\/post-3-gallery-2-min.jpg\"data-width=\"450\" data-height=\"700\" data-index=\"2\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/rxhealthcare.in\/wp-content\/uploads\/elementor\/thumbs\/post-3-gallery-2-min-qablpy2wt654o4q7xf7oka8wdagfyek58z1e0ommra.jpg\"alt=\"post-3-gallery-2-min\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Our Latest Work WE ARE CREATIVE AGENCY Accum luctus dolor sit amet, consectetuer adipiscing elit, sed diam nonummy nibh euismod<\/p>\n","protected":false},"featured_media":473,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","project-cat":[34],"_links":{"self":[{"href":"https:\/\/rxhealthcare.in\/index.php\/wp-json\/wp\/v2\/portfolio\/556"}],"collection":[{"href":"https:\/\/rxhealthcare.in\/index.php\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/rxhealthcare.in\/index.php\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/rxhealthcare.in\/index.php\/wp-json\/wp\/v2\/comments?post=556"}],"version-history":[{"count":0,"href":"https:\/\/rxhealthcare.in\/index.php\/wp-json\/wp\/v2\/portfolio\/556\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rxhealthcare.in\/index.php\/wp-json\/wp\/v2\/media\/473"}],"wp:attachment":[{"href":"https:\/\/rxhealthcare.in\/index.php\/wp-json\/wp\/v2\/media?parent=556"}],"wp:term":[{"taxonomy":"project-cat","embeddable":true,"href":"https:\/\/rxhealthcare.in\/index.php\/wp-json\/wp\/v2\/project-cat?post=556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}